{"id":1454,"date":"2017-07-19T10:13:33","date_gmt":"2017-07-19T09:13:33","guid":{"rendered":"http:\/\/xn--sentier-vitalit-pnb.fr\/?p=1454"},"modified":"2020-11-23T14:57:10","modified_gmt":"2020-11-23T13:57:10","slug":"equilibre-acido-basique-mais-de-quoi-sagit-il","status":"publish","type":"post","link":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/","title":{"rendered":"\u00c9quilibre acido-basique mais de quoi s&rsquo;agit-il ?"},"content":{"rendered":"<p data-blogger-escaped-style=\"text-align: center;\"><span style=\"color: #000000;\">L&rsquo;\u00e9quilibre acido-basique\u00a0est une notion indispensable en naturopathie. Pour \u00eatre pr\u00e9cis, il est plus juste de parler plut\u00f4t de \u00ab\u00a0<em>m\u00e9canisme d&rsquo;acidose m\u00e9tabolique latente nutritionnel<\/em>\u00ab\u00a0.\u00a0<\/span><\/p>\n<p data-blogger-escaped-style=\"text-align: center;\">La bonne r\u00e9gulation du pH (= potentiel Hydrog\u00e8ne) est un gage de bonne sant\u00e9.\u00a0L&rsquo;acidose est en effet bien souvent le nid de nombreuses pathologies:<\/p>\n<ul style=\"list-style-type: circle;\">\n<li>rhumatismes<\/li>\n<li>\u00a0ost\u00e9oporose<\/li>\n<li>tendinite<\/li>\n<li>arthrose, arthrite<\/li>\n<li>reflux gastrique<\/li>\n<li>fissures aux coins des l\u00e8vres,<\/li>\n<li>dermatoses s\u00e8ches,<\/li>\n<li>calculs r\u00e9naux ou v\u00e9siculaires&#8230;..<\/li>\n<\/ul>\n<h4><strong><span style=\"color: #138585;\">Quel est son m\u00e9canisme ? Comment maintenir un bel \u00e9quilibre ?<\/span><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p>Pour \u00eatre en bonne sant\u00e9 notre organisme doit maintenir un pH sanguin de 7,40 soit l\u00e9g\u00e8rement alcalin.<\/p>\n<p>Nos liquides organiques et nos tissus ont des pH diff\u00e9rents qui peuvent l\u00e9g\u00e8rement varier \u00a0mais notre sang, lui, doit \u00a0rester dans des fluctuations de 0,04 car au del\u00e0 le pronostic vital est mis en jeu.\u00a0D\u00e8s lors, notre corps va tout mettre en place pour maintenir cet \u00e9quilibre.<\/p>\n<p>pH&lt; 7.36 implique une acidose sanguine<\/p>\n<p>pH&gt; 7,44 implique une alcalose sanguine<\/p>\n<p>Notre corps va avoir une tendance \u00e0 s&rsquo;acidifier surtout avec notre mode de vie actuel ! Stress, alimentation d\u00e9s\u00e9quilibr\u00e9e, manque d&rsquo;activit\u00e9s physiques sont autant de facteurs d&rsquo;acidification.<\/p>\n<p>Face \u00e0 ce d\u00e9s\u00e9quilibre, le corps va utiliser diff\u00e9rents moyens pour r\u00e9tablir l&rsquo;hom\u00e9ostasie.<\/p>\n<h5><span style=\"color: #250869;\"><strong><u><em data-blogger-escaped-style=\"background-color: #a2c4c9;\">Notions d&rsquo;acides et de bases ?<\/em><\/u><\/strong><\/span><\/h5>\n<p>Chimiquement \u00a0les\u00a0<span style=\"color: #de142c;\"><strong>acides<\/strong><\/span>\u00a0sont d\u00e9finis comme des substances\u00a0capables\u00a0de lib\u00e9rer un ion hydrog\u00e8ne (H+).<\/p>\n<p>Les acides sont corrosifs, dans l&rsquo;alimentation on distingue\u00a0facilement\u00a0les produits acides gr\u00e2ce \u00e0 nos papilles. Cependant le go\u00fbt n&rsquo;est pas un moyen\u00a0infaillible\u00a0pour d\u00e9terminer le\u00a0caract\u00e8re acide d&rsquo;un aliment!<\/p>\n<p>En effet, nous verrons plus tard qu&rsquo;il existe des aliments acides et des aliments acidifiants. Ces derniers n&rsquo;auront pas un go\u00fbt acide car diff\u00e9rentes substances neutralisent ce go\u00fbt. Prenons l&rsquo;exemple de la viande ou des c\u00e9r\u00e9ales ou bien encore la c\u00e9l\u00e8bre boisson au cola ; ils ne sont pas acides en bouche et pourtant ils sont bien acidifiants.<\/p>\n<p>Le cola peut m\u00eame \u00eatre utilis\u00e9 comme d\u00e9tergeant pour vos toilettes &#8230;<\/p>\n<p>Les\u00a0<span style=\"color: #0856cc;\"><strong>bases<\/strong>\u00a0<\/span>elles sont capables de capter un ou plusieurs protons H+. Dans l&rsquo;alimentation une tr\u00e8s grande partie des l\u00e9gumes sont alcalinisants.<\/p>\n<p>La teneur en min\u00e9raux permet \u00e9galement de d\u00e9duire si un aliment sera plus alcalinisant ou acidifiant.\u00a0Les min\u00e9raux et oligo\u00e9l\u00e9ments sont aussi class\u00e9s selon leur pouvoir acidifiant ou alcalinisant.<\/p>\n<p>&nbsp;<\/p>\n<table style=\"height: 121px; border-color: #ccc8c8;\" width=\"635\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 660px;\"><span style=\"color: #de142c;\">Min\u00e9raux acides<\/span><\/td>\n<td style=\"width: 621px;\"><span style=\"color: #4896f0;\">Min\u00e9raux basiques <\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 660px;\">\n<ul style=\"list-style-type: square;\">\n<li>Soufre<\/li>\n<li>Chlore<\/li>\n<li>Phosphore<\/li>\n<li>Fluor<\/li>\n<li>Iode<\/li>\n<li>Silice<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 621px;\">\n<ul style=\"list-style-type: square;\">\n<li>Calcium<\/li>\n<li>Potassium<\/li>\n<li>Magn\u00e9sium<\/li>\n<li>Sodium<\/li>\n<li>Fer<\/li>\n<li>Mangan\u00e8se<\/li>\n<li>Cobalt<\/li>\n<li>Cuivre<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Il existe des comp\u00e9titions et des\u00a0interactions\u00a0entre chacun d&rsquo;eux, il s&rsquo;agit l\u00e0 aussi d&rsquo;un juste \u00e9quilibre ! Par exemple, le calcium est moins bien absorb\u00e9 par l&rsquo;organisme s\u2019il y a un exc\u00e8s de phosphore ou de magn\u00e9sium et vice versa &#8230;<br \/>\nN&rsquo;\u00e9tant pas synth\u00e9tis\u00e9s par l&rsquo;organisme, les min\u00e9raux et oligo-\u00e9l\u00e9ments sont apport\u00e9s obligatoirement par l&rsquo;alimentation.\u00a0De mani\u00e8re g\u00e9n\u00e9rale plus un aliment est riches en potassium, magn\u00e9sium, calcium &#8230; plus il sera alcalinisant. Les aliments raffin\u00e9s ont perdus leurs min\u00e9raux et sont acidifiants.<\/p>\n<h5 data-blogger-escaped-style=\"margin-bottom: 0.0001pt;\"><span style=\"color: #db4444;\">\u00a0<strong><u><em>Acides forts et acides faibles ?<\/em><\/u><\/strong><\/span><\/h5>\n<p>Juste une derni\u00e8re petite notion de chimie! Les acides ne se pr\u00e9sentent jamais \u00e0 l&rsquo;\u00e9tat libres ou seuls, ils sont le plus souvent li\u00e9s \u00e0 une base.<\/p>\n<p>\u2192 On parle d&rsquo;<u>acide FAIBLE<\/u>\u00a0lorsque celui-ci est li\u00e9 \u00e0 une base forte, la r\u00e9action est totale et va donner des ions hydroxydes.<\/p>\n<p>Les acides faibles sont facilement neutralis\u00e9s par l&rsquo;organisme.<\/p>\n<p>\u2192 On parle d&rsquo;<strong><u>acide FORT<\/u><\/strong>\u00a0lorsque celui-ci est li\u00e9 \u00e0 une base faible, dans l&rsquo;eau il se dissocie compl\u00e8tement en ions H+.<\/p>\n<p>Les acides forts sont plus stables et donc plus difficiles \u00e0 neutraliser par notre organisme.<\/p>\n<p>L&rsquo;association d&rsquo;un acide faible et de sa base conjugu\u00e9e ou d&rsquo;une base faible et de son acide conjugu\u00e9 est appel\u00e9e <strong>SUBSTANCE TAMPON<\/strong>.<\/p>\n<p>Ces substances sont capables de lib\u00e9rer ou de capturer des acides pour ainsi \u00e9quilibrer une solution.<\/p>\n<h4><span style=\"color: #99cc00;\"><strong><u><em data-blogger-escaped-style=\"background-color: #93c47d;\">QUELLES SONT LES D\u00c9FENSES\u00a0DE NOTRE ORGANISME FACE A L&rsquo;ACIDIFICATION?\u00a0<\/em><\/u><\/strong><\/span><\/h4>\n<p>En cas d&rsquo;exc\u00e8s d&rsquo;acide notre corps va essayer de chasser ces acides en activant nos \u00e9monctoires.<\/p>\n<ul style=\"list-style-type: circle;\">\n<li>\u00a0Les <strong>poumons<\/strong> interviennent rapidement pour chasser les acides faibles et volatiles. La respiration et surtout l&rsquo;activit\u00e9 physique qui met en jeu le syst\u00e8me cardio-respiratoire vont\u00a0permettent\u00a0d\u2019\u00e9vacuer\u00a0rapidement ces acides.<\/li>\n<li>Les acides forts quant \u00e0 eux sont \u00e9limin\u00e9s par les <strong>reins<\/strong> \u00e0 travers les urines. Le pH de nos urines est un moyen facile et rapide d&rsquo;\u00e9valuer notre \u00e9quilibre acido-basique. Il suffit pour cela d&rsquo;avoir du papier tournesol que l&rsquo;on trouve facilement en pharmacie.<\/li>\n<li>Le <strong>foie<\/strong> souvent oubli\u00e9 dans l&rsquo;\u00e9quilibre acido-basique permet \u00e9galement de drainer les acides biliaires. Il d\u00e9grade \u00e9galement l&rsquo;acide lactique, participe au cycle de l&rsquo;acide urique, de l&rsquo;ur\u00e9e, de la glutamine ceci en collaboration avec les reins et les poumons. Selon Richard Haas \u00ab\u00a0le foie a le plus grand r\u00f4le \u00e0 jouer dans l&rsquo;EAB\u00a0\u00bb.<\/li>\n<li>La <strong>peau<\/strong> avec les glandes sudoripares (+ de 2 millions)\u00a0qui fonctionnent tel des petits reins, permet d&rsquo;\u00e9liminer les acides forts par la sueur.<\/li>\n<\/ul>\n<p>Quand les \u00e9monctoires sont d\u00e9pass\u00e9s par un exc\u00e8s d&rsquo;acides \u00e0 \u00e9liminer, l&rsquo;organisme met en place des\u00a0<strong>syst\u00e8mes tampons<\/strong>. On parle de tampons lorsqu&rsquo;un acide faible et sa base conjugu\u00e9e ou une base faible et son acide conjugu\u00e9 sont pr\u00e9sents en m\u00eame temps. Ces substances sont capables de neutraliser, de \u00ab\u00a0tamponner\u00a0\u00bb un ajout d&rsquo;acide ou de base pour maintenir le pH. L&rsquo;organisme utilise diff\u00e9rents syst\u00e8mes tampons:<\/p>\n<ul style=\"list-style-type: disc;\">\n<li>Le\u00a0<u data-blogger-escaped-style=\"font-size: x-large;\">syst\u00e8me<\/u><u data-blogger-escaped-style=\"font-size: x-large;\">\u00a0<\/u><u data-blogger-escaped-style=\"font-size: x-large;\">tampons\u00a0<\/u><u data-blogger-escaped-style=\"font-size: x-large;\">acide\u00a0<\/u><u data-blogger-escaped-style=\"font-size: x-large;\">carbonique\/bicarbonate<\/u>\u00a0qui permet de r\u00e9guler le pH sanguins rapidement gr\u00e2ce \u00e0 la respiration et d&rsquo;une mani\u00e8re plus lente mais plus longue par les reins.<\/li>\n<li>Le <u>syst\u00e8me tampons des\u00a0<\/u><u>prot\u00e9ines<\/u>\u00a0qui sont form\u00e9es d&rsquo;un groupement amines et d&rsquo;un groupement carboxyle. En cas d&rsquo;acidose c&rsquo;est la fonction amine qui va jouer le r\u00f4le de base et va capter des acides (H+) et en cas d&rsquo;alcalose c&rsquo;est la fonction acide qui va lib\u00e9rer des ions H+.<\/li>\n<li>Le <u>syst\u00e8me tampon de l&rsquo;os<\/u> qui va neutraliser les acides gr\u00e2ce aux min\u00e9raux basiques (Mg++, Ca+, K+)\u00a0contenus dans les os, cheveux, dents &#8230; on assiste en cas de forte acidose m\u00e9tabolique \u00e0 une forte d\u00e9min\u00e9ralisation.<\/li>\n<\/ul>\n<h4 data-blogger-escaped-style=\"margin-bottom: 0.0001pt;\"><strong><span style=\"text-decoration: underline;\"><span style=\"color: #b867b6; text-decoration: underline;\">QUELLES SONT LES CONS\u00c9QUENCES DE L&rsquo;ACIDOSE M\u00c9TABOLIQUE LATENTE ?<\/span><\/span><\/strong><\/h4>\n<ol>\n<li><u><strong>Baisse de l&rsquo;activit\u00e9 enzymatique:<\/strong><\/u>Les enzymes sont des\u00a0prot\u00e9ines\u00a0qui interviennent dans de nombreuses r\u00e9actions biochimiques de l&rsquo;organisme. Pour \u00eatre pleinement efficaces elles doivent \u00ab\u00a0baigner\u00a0\u00bb dans un milieu \u00ab\u00a0sain\u00a0\u00bb dont le pH est stable! L&rsquo;acidit\u00e9 peut perturber de nombreuses r\u00e9actions enzymatiques comme la production de\u00a0prot\u00e9ines,\u00a0d&rsquo;hormones, la production d&rsquo;ATP &#8230; d&rsquo;o\u00f9 une fatigue g\u00e9n\u00e9rale.<\/li>\n<li><u data-blogger-escaped-style=\"text-indent: -18pt;\"><strong>Irritations et inflammations de nos tissus : <\/strong><\/u>Les acides exc\u00e9dentaires sont stock\u00e9s dans les tissus conjonctifs, les articulations et les graisses; On parle d&rsquo;acidose tissulaire L&rsquo;ensemble des tissus est fragilis\u00e9 et un terrain inflammatoire s&rsquo;installe.\u00a0La sueur plus acide entra\u00eene des rougeurs, les urines charg\u00e9es en acides peuvent donner des cystites. Au niveau articulaire, les acides agressent les cartilages entra\u00eenant des probl\u00e8mes rhumatismales.<\/li>\n<li><u data-blogger-escaped-style=\"text-indent: -18pt;\"><strong>Forte d\u00e9min\u00e9ralisation: <\/strong><\/u>Pour maintenir le pH sanguin, le phosphate de calcium du tissu osseux se solubilise pour passer dans la circulation sanguine o\u00f9 il peut capter les ions H+ en exc\u00e8s. Lors de l&rsquo;acidose chronique il y a une forte d\u00e9min\u00e9ralisation qui fragilise les os; sensibilise les dents aux caries et aux d\u00e9chaussement; les ongles sont cassants, stri\u00e9s; les cheveux sont fins et cassants; les articulations sont moins souples &#8230;<\/li>\n<li><u><strong>Baisse des d\u00e9fenses immunitaires:<\/strong><\/u> Fragilis\u00e9es par la d\u00e9min\u00e9ralisation, l&rsquo;inflammation globale des tissus la peau ne joue plus correctement sont r\u00f4le de barri\u00e8re. De m\u00eame les organes lympho\u00efdes sont ralentis favorisant les infections \u00e0 r\u00e9p\u00e9titions.<\/li>\n<li><u><strong>\u00ab\u00a0Encrassement\u00a0\u00bb des \u00e9monctoires:<\/strong><\/u> Acide\u00a0+ base donne des sels, ces sels ou cristaux form\u00e9s pour \u00e9quilibrer le pH vont se loger \u00e9galement dans les organes formant des calculs biliaires, calculs r\u00e9naux &#8230;\u00a0Ils s&rsquo;accumulent aussi au niveau articulaire entra\u00eenant de \u00a0 l&rsquo; arthrose.<\/li>\n<\/ol>\n<p>Selon le degr\u00e9 d&rsquo;acidit\u00e9, le\u00a0temp\u00e9rament\u00a0de la personne, la tendance \u00e0\u00a0l&rsquo;acidose chronique entra\u00eene de nombreuses affections:\u00a0arthrites, cheveux et ongles cassants, n\u00e9vralgies, cystites, tendinites, acidit\u00e9 gastrique&#8230;<\/p>\n<p>Globalement les personnes qui ont une acidose m\u00e9tabolique latente nutritionnel sont souvent plus frileuses, leur syst\u00e8me immunitaire est affaiblit. L&rsquo;encrassement du tissu conjonctif pr\u00e9dispose \u00e0 toute sorte de perturbations: rhumatismes, douleurs articulaires, crampes, spasmes, inflammations diverses, allergies &#8230; s&rsquo;accompagnant en g\u00e9n\u00e9rale d&rsquo;une fatigue extr\u00eame. La carence en min\u00e9raux \u00a0en particulier en magn\u00e9sium entra\u00eene une grande fatigue, les nerfs sont \u00e0 \u00ab\u00a0vifs\u00a0\u00bb !<\/p>\n<h4 data-blogger-escaped-style=\"margin-bottom: 0.0001pt;\"><span style=\"color: #ff99cc;\"><strong><span style=\"text-decoration: underline;\">QUELLES EN SONT LES CAUSES?<\/span><\/strong><\/span><\/h4>\n<p>Le stress et le mode de vie moderne sont les premi\u00e8res causes d&rsquo;acidification de notre organisme.<\/p>\n<p><span style=\"color: #0c98cf;\"><strong><u>LE STRESS\u00a0<\/u><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"lazyload wp-image-1414 alignleft\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27196%27%20height%3D%27147%27%20viewBox%3D%270%200%20196%20147%27%3E%3Crect%20width%3D%27196%27%20height%3D%27147%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2016\/06\/relax-955798.jpg\" alt=\"\" width=\"196\" height=\"147\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En cas de stress nous sommes en hyper sympathicotonie, cela entra\u00eene une forte perte des min\u00e9raux\u00a0notamment\u00a0le magn\u00e9sium et le\u00a0calcium par les urines.\u00a0Le syst\u00e8me nerveux qui est sur-sollicit\u00e9 \u00e9puise ces\u00a0r\u00e9serves\u00a0de\u00a0magn\u00e9sium.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0c98cf;\"><strong data-blogger-escaped-style=\"line-height: 22.8266677856445px;\"><u>L&rsquo;ALIMENTATION\u00a0<\/u><\/strong><\/span><\/p>\n<p>On peut classer les aliments en trois cat\u00e9gories :<\/p>\n<p>\u21d2\u00a0<u>Les aliments acides = acides directs<\/u><\/p>\n<ul style=\"list-style-type: square;\">\n<li>fruits acides\u00a0et leurs jus (agrumes, fruits rouges, kiwis, abricots, tomates &#8230; tous sauf la banane et la\u00a0ch\u00e2taigne)<\/li>\n<li>L\u00e9gumes acides\u00a0(oseille, \u00e9pinards, asperge &#8230;)<\/li>\n<li>Aliments lacto-ferment\u00e9s\u00a0:\u00a0laitages acides: yaourts, k\u00e9fir, choucroute, fromage blanc &#8230;<\/li>\n<li>Vinaigre et condiments<\/li>\n<li>Vin,\u00a0champagne,\u00a0cidre\u00a0&#8230;<\/li>\n<li>Certains\u00a0m\u00e9dicaments, additifs<\/li>\n<li>Le\u00a0miel<\/li>\n<\/ul>\n<p>Ces aliments sont plus ou moins acidifiants selon la quantit\u00e9 ing\u00e9r\u00e9e, le temp\u00e9rament, la vitalit\u00e9, la saison, l&rsquo;heure de consommation. 17h est l&rsquo;heure id\u00e9al pour \u00e9liminer les acides des fruits et de mani\u00e8re g\u00e9n\u00e9rale une personne avec un temp\u00e9rament \u00ab\u00a0chaud\u00a0\u00bb, avec une bonne vitalit\u00e9 m\u00e9tabolisera plus facilement ces acides faibles.<\/p>\n<p>\u21d2<u>Les aliments acidifiants = acides indirects<\/u><\/p>\n<p>Les aliments riches en\u00a0prot\u00e9ines, en hydrate de carbone ou en lipides<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignleft wp-image-1475\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27288%27%20height%3D%27204%27%20viewBox%3D%270%200%20288%20204%27%3E%3Crect%20width%3D%27288%27%20height%3D%27204%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"http:\/\/xn--sentier-vitalit-pnb.fr\/wp-content\/uploads\/2017\/04\/fat-foods-1487599-300x213.jpg\" alt=\"\" width=\"288\" height=\"204\" \/><\/p>\n<ul style=\"list-style-type: square;\">\n<li>Prot\u00e9ines\u00a0animales\u00a0surtout la viande rouge, les charcuteries, les gibiers, les abats, le fromage au lait de vache<\/li>\n<li>Prot\u00e9ines\u00a0v\u00e9g\u00e9tales:\u00a0surtout les c\u00e9r\u00e9ales<\/li>\n<li>Les\u00a0purines\u00a0contenues dans le caf\u00e9, le th\u00e9 noir, les l\u00e9gumineuses, levure alimentaires<\/li>\n<li>Les\u00a0graisses satur\u00e9es\u00a0: animales et v\u00e9g\u00e9tales raffin\u00e9s et hydrog\u00e9n\u00e9es<\/li>\n<li>Les\u00a0hydrates de carbones\u00a0tel que les p\u00e2tes, farines, pain, sucre &#8230; d&rsquo;autant plus lorsqu&rsquo;ils sont raffin\u00e9s car on leur \u00e0 enlever tous leurs min\u00e9raux au pouvoir alcalinisant.\u00a0<img decoding=\"async\" class=\"lazyload alignright size-thumbnail wp-image-1474\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27150%27%20height%3D%27150%27%20viewBox%3D%270%200%20150%20150%27%3E%3Crect%20width%3D%27150%27%20height%3D%27150%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"http:\/\/xn--sentier-vitalit-pnb.fr\/wp-content\/uploads\/2017\/04\/caramel-1952996_1920-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u21d2<u>Les aliments alcalinisants\u00a0<img decoding=\"async\" class=\"lazyload size-medium wp-image-1148 alignleft\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27209%27%20height%3D%27300%27%20viewBox%3D%270%200%20209%20300%27%3E%3Crect%20width%3D%27209%27%20height%3D%27300%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"http:\/\/xn--sentier-vitalit-pnb.fr\/wp-content\/uploads\/2016\/10\/vegetables-1319821-209x300.png\" alt=\"\" width=\"209\" height=\"300\" \/><\/u><\/p>\n<p>A consommer en priorit\u00e9 et en <span style=\"text-decoration: underline;\">plus grande quantit\u00e9<\/span> que les \u00a0aliments acidifiants pour contre balancer leurs effets. Les aliments alcalinisants sont\u00a0principalement\u00a0les l\u00e9gumes verts et color\u00e9s (sauf tomate, asperge, cresson) mais aussi les pomme de terre, les bananes,\u00a0ch\u00e2taignes, millet (une des rares c\u00e9r\u00e9ales alcalinisantes),avocat, les fruits secs (sauf abricot) &#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>Les aliments que nous ing\u00e9rons ont une grande influence sur l&rsquo;\u00e9quilibre acido-basique mais la qualit\u00e9 de la digestion est \u00e9galement importante. <strong>Une flore intestinale d\u00e9s\u00e9quilibr\u00e9e, une parois intestinale endommag\u00e9e, des associations alimentaires inad\u00e9quates sont sources d&rsquo;acidose endog\u00e8ne.<\/strong><\/p>\n<p><u>\u21d2Les fermentations intestinales = acidose endog\u00e8ne<\/u><\/p>\n<p>Les fermentations digestives sont dues:<\/p>\n<ul style=\"list-style-type: square;\">\n<li>\u00a0incompatibilit\u00e9s\u00a0alimentaires\u00a0(f\u00e9culents\u00a0+\u00a0fruits \/prot\u00e9ines\u00a0fortes\u00a0+ f\u00e9culents\/ amidon \/ aliments acides)<\/li>\n<li>la suralimentation<\/li>\n<li>les grignotages<\/li>\n<li>le stress<\/li>\n<\/ul>\n<p>\u21d2<u>Les carences nutritionnelles<\/u><\/p>\n<p>Les carences en particulier en vitamines B, magn\u00e9sium et en oligo-\u00e9l\u00e9ments entra\u00eene le dysfonctionnement du cycle de Krebs.\u00a0Ce cycle permet \u00e0\u00a0notre organisme de produire de l&rsquo;\u00e9nergie. Ces\u00a0vitamines, ces min\u00e9raux sont essentiels pour que ces r\u00e9actions en cha\u00eene se produisent correctement et aboutissent \u00e0 la production d&rsquo;ATP = \u00e9nergie.<\/p>\n<p>Toutes ces r\u00e9actions chimiques produisent des acides, s&rsquo;il manque des cofacteurs le cycle se bloque et il y a une accumulation d&rsquo;acides dans l&rsquo;organisme et par ailleurs moins d&rsquo;\u00e9nergie d&rsquo;o\u00f9 une fatigue g\u00e9n\u00e9rale et une\u00a0acidification\u00a0tissulaire. Ces acides forts se fixent sur les fibres d&rsquo;\u00e9lastine du tissus conjonctif. Ce tissus fait partie du m\u00e9senchyme tissus de soutien de l&rsquo;ensemble de l&rsquo;organisme. Il permet une bonne oxyg\u00e9nation cellulaire, une bonne hydratation, il apporte les nutriments aux cellules et \u00e9vacue leurs d\u00e9chets. L&rsquo;exc\u00e8s d&rsquo;acide transforme la structure de ce tissus\u00a0collo\u00efdale, il a alors tendance \u00e0 se solidifier en \u00ab\u00a0gel\u00a0\u00bb. Il en d\u00e9coule forc\u00e9ment une moins bonne communication inter-cellulaire et une mauvaise oxyg\u00e9nation des tissus.<\/p>\n<p><span style=\"color: #0c98cf;\"><u><strong>LA S\u00c9DENTARIT\u00c9\u00a0ET LA SOUS-OXYG\u00c9NATION:<\/strong><\/u><\/span><\/p>\n<p>Le sport est le seul moyen d&rsquo;activer tous nos \u00e9monctoires! Il permet d&rsquo;augmenter la fr\u00e9quence respiratoire ainsi notre organisme est bien oxyg\u00e9n\u00e9 et draine les acides faibles. L&rsquo;activit\u00e9 physique fait transpirer et par la m\u00eame occasion draine les acides par les glandes sudoripares.<\/p>\n<p><span style=\"color: #0c98cf;\"><u><strong>LES \u00c9LIMINATIONS\u00a0EMONCTORIELLES INSUFFISANTES<\/strong><\/u><\/span><\/p>\n<p>Une insuffisance h\u00e9patique, r\u00e9nale, cutan\u00e9e emp\u00eache de drainer correctement les acides de l&rsquo;organisme. De m\u00eame la s\u00e9dentarit\u00e9, une mauvaise hydratation, une alimentation pauvre en fibre entra\u00eenent une accumulation des acides dans l&rsquo;organisme.<\/p>\n<p><span style=\"color: #0c98cf;\"><u><strong>CERTAINS TRAITEMENTS:<\/strong><\/u><\/span><\/p>\n<p>Anti-inflammatoires, cortico\u00efdes, aspirine, morphine g\u00e9n\u00e8rent de l&rsquo;acidit\u00e9.<\/p>\n<p><span style=\"color: #0c98cf;\"><strong><u>LE MANQUE DE SOMMEIL OU LE TRAVAIL DE NUIT<\/u><\/strong><\/span><\/p>\n<p>En activit\u00e9 la journ\u00e9e notre organisme produit normalement des d\u00e9riv\u00e9s acides. En exc\u00e8s si les \u00e9monctoires ne peuvent les \u00e9vacu\u00e9s, ils sont stock\u00e9s dans les tissus conjonctifs. La nuit p\u00e9riode de repos pour le corps ces acides vont \u00eatre \u00e9limin\u00e9s. Un manque de repos, des nuits trop courtes, le travail de nuit ou bien un d\u00eener pris tard le soir sont autant de facteurs qui emp\u00eachent l&rsquo;organisme de se r\u00e9g\u00e9n\u00e9rer la nuit. En effet, la nuit est un moment privil\u00e9gier pour notre corps cela lui permet, oserais-je dire, de \u00ab\u00a0s\u2019 auto-nettoyer\u00a0\u00bb,se r\u00e9parer et de recharger ses batteries ! Un d\u00eener pris trop tard ou bien trop copieux et trop long \u00e0 dig\u00e9rer va occuper notre corps et emp\u00eacher ce travail de \u00ab\u00a0r\u00e9paration\u00a0\u00bb; de m\u00eame qu&rsquo;une nuit trop courte ou qu&rsquo;un travail en horaires d\u00e9cal\u00e9s.<\/p>\n<h4><span style=\"color: #72c433;\"><strong><u>COMMENT CORRIGER SON \u00c9QUILIBRE\u00a0ACIDO-BASIQUE?<\/u><\/strong><\/span><\/h4>\n<p><strong>\u21d2\u00a0Adopter\u00a0une\u00a0<\/strong><strong>alimentation \u00e9quilibr\u00e9e et alcalinisante<\/strong>\u00a0:<\/p>\n<p>\u00b0<u>Riche en l\u00e9gumes\u00a0alcalinisants:<\/u><\/p>\n<p>-l\u00e9gumes verts crus ou cuits comme la salade, haricots verts, choux &#8230; sauf \u00e9pinard, oseille<\/p>\n<p>&#8211; l\u00e9gumes color\u00e9s comme les betteraves, carottes, poivrons &#8230;<\/p>\n<p>-les ch\u00e2taignes tr\u00e8s riche en potassium,\u00a0la pomme de terre, la patate douce &#8230;<br \/>\n\u00b0 <u>Limitez la consommation de produits acidifiants<\/u> en particulier viandes rouges, charcuteries, c\u00e9r\u00e9ales raffin\u00e9es, boissons industrielles, huile raffin\u00e9es, fromages forts.<br \/>\n\u00b0<u>Consommez vos fruits en fin d&rsquo;apr\u00e8s-midi<\/u> \u00a0quand votre organisme \u00e9limine mieux les acides.<br \/>\n\u00b0<span style=\"text-decoration: underline;\">Consommez des fruits secs:<\/span> dattes, raisins, figues &#8230; sauf abricots et pommes qui sont acides.<br \/>\n\u00b0<u>Bannissez les produits industriels et raffin\u00e9s<\/u> et remplacez les par des farines bio compl\u00e8tes, du sucre int\u00e9gral &#8230;<br \/>\n\u00b0 <span style=\"text-decoration: underline;\">Supprimer ou au moins r\u00e9duisez votre consommation d&rsquo;excitants<\/span> (caf\u00e9, th\u00e9, cola, tabac &#8230;)<\/p>\n<p><strong>\u21d2 \u00a0<\/strong><strong>Drainer les acides en ouvrant vos \u00e9monctoires<\/strong>:<\/p>\n<p><u>Poumons:<\/u> pratiquer une activit\u00e9s physiques pour mettre en route le syst\u00e8me cardio-respiratoire.<\/p>\n<p><u>Reins:<\/u> buvez une eau peu min\u00e9ralis\u00e9es (r\u00e9sidus \u00e0 secs &lt; 150mg\/L) Consommez des tisanes ou compl\u00e9ments de plantes drainantes (feuilles de cassis, queues de cerises, aubier de tilleul, busserole, pissenlit &#8230;)<\/p>\n<p><u>Peau:<\/u> Faites r\u00e9guli\u00e8rement des s\u00e9ances de sauna, de l&rsquo;exercice physique pour transpirer<\/p>\n<p><strong>\u21d2 \u00a0Revitaliser, remin\u00e9ralis\u00e9 :<\/strong><\/p>\n<p>Par une alimentation hypotoxique, riches en min\u00e9raux (aliments crus, graines germ\u00e9es, ol\u00e9agineux, algues, m\u00e9lasse noire,\u00a0ch\u00e2taignes\u00a0&#8230;) Faire une cure d&rsquo;eau <a href=\"http:\/\/www.hydroxydase.fr\/crbst_5.html\" data-blogger-escaped-target=\"_blank\">hydroxydase<\/a>\u00a0ou prendre des complexes riches en min\u00e9raux K+, Ca++, Mg+ &#8230; Veillez \u00e9galement \u00e0 l&rsquo;\u00e9quilibre de votre flore intestinale et l&rsquo;int\u00e9grit\u00e9 de votre muqueuse.<\/p>\n<p><strong>\u21d2 \u00a0Gestion du stress:<\/strong><\/p>\n<p><img decoding=\"async\" class=\"lazyload alignleft wp-image-1466\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27219%27%20height%3D%27144%27%20viewBox%3D%270%200%20219%20144%27%3E%3Crect%20width%3D%27219%27%20height%3D%27144%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"http:\/\/xn--sentier-vitalit-pnb.fr\/wp-content\/uploads\/2017\/04\/relax-1183533-300x197.jpg\" alt=\"\" width=\"219\" height=\"144\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Relaxation, m\u00e9ditation, yoga &#8230; accordez-vous des moments de d\u00e9tentes et apprenez \u00e0 vivre dans le moment pr\u00e9sent.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Votre naturopathe pourra vous aidez dans votre d\u00e9marche en vous apportant des conseils personnalis\u00e9s et pertinents selon votre temp\u00e9rament.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9quilibre acido-basique\u00a0est une notion indispensable en naturopathie. Pour \u00eatre pr\u00e9cis, il est plus juste de parler plut\u00f4t de \u00ab\u00a0m\u00e9canisme d&rsquo;acidose m\u00e9tabolique latente nutritionnel\u00ab\u00a0.\u00a0 La bonne<\/p>\n","protected":false},"author":2,"featured_media":1455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[72],"tags":[63,64,61,60,31,62],"class_list":["post-1454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-naturopathie","tag-arthrose","tag-demineralisation","tag-eab","tag-equilibre-acido-basique","tag-fatigue","tag-sante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9quilibre acido-basique mais de quoi s&#039;agit-il ? - Sant\u00e9Onaturel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9quilibre acido-basique mais de quoi s&#039;agit-il ? - Sant\u00e9Onaturel\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;\u00e9quilibre acido-basique\u00a0est une notion indispensable en naturopathie. Pour \u00eatre pr\u00e9cis, il est plus juste de parler plut\u00f4t de \u00ab\u00a0m\u00e9canisme d&rsquo;acidose m\u00e9tabolique latente nutritionnel\u00ab\u00a0.\u00a0 La bonne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/\" \/>\n<meta property=\"og:site_name\" content=\"Sant\u00e9Onaturel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/about\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-19T09:13:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-23T13:57:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2017\/04\/rocks-1524171_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1438\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marjorie DECLOQUEMENT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marjorie DECLOQUEMENT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/\",\"url\":\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/\",\"name\":\"\u00c9quilibre acido-basique mais de quoi s'agit-il ? - Sant\u00e9Onaturel\",\"isPartOf\":{\"@id\":\"https:\/\/naturopathe35.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2017\/04\/rocks-1524171_1920.jpg\",\"datePublished\":\"2017-07-19T09:13:33+00:00\",\"dateModified\":\"2020-11-23T13:57:10+00:00\",\"author\":{\"@id\":\"https:\/\/naturopathe35.fr\/#\/schema\/person\/4466d62599687978be8f5a0f1df3f7ca\"},\"breadcrumb\":{\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#primaryimage\",\"url\":\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2017\/04\/rocks-1524171_1920.jpg\",\"contentUrl\":\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2017\/04\/rocks-1524171_1920.jpg\",\"width\":1438,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/naturopathe35.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9quilibre acido-basique mais de quoi s&rsquo;agit-il ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/naturopathe35.fr\/#website\",\"url\":\"https:\/\/naturopathe35.fr\/\",\"name\":\"Sant\u00e9Onaturel\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/naturopathe35.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/naturopathe35.fr\/#\/schema\/person\/4466d62599687978be8f5a0f1df3f7ca\",\"name\":\"Marjorie DECLOQUEMENT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/naturopathe35.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/da8b5dfb971dc234578fd220ae090cd190a7c2abd7954496397a2b38e10aac2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/da8b5dfb971dc234578fd220ae090cd190a7c2abd7954496397a2b38e10aac2f?s=96&d=mm&r=g\",\"caption\":\"Marjorie DECLOQUEMENT\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/about\/\",\"https:\/\/www.instagram.com\/santeonaturel_rennes\/\",\"https:\/\/www.linkedin.com\/in\/marjorie-decloquement-b6482484\/\"],\"url\":\"https:\/\/naturopathe35.fr\/index.php\/author\/marjorie\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9quilibre acido-basique mais de quoi s'agit-il ? - Sant\u00e9Onaturel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9quilibre acido-basique mais de quoi s'agit-il ? - Sant\u00e9Onaturel","og_description":"L&rsquo;\u00e9quilibre acido-basique\u00a0est une notion indispensable en naturopathie. Pour \u00eatre pr\u00e9cis, il est plus juste de parler plut\u00f4t de \u00ab\u00a0m\u00e9canisme d&rsquo;acidose m\u00e9tabolique latente nutritionnel\u00ab\u00a0.\u00a0 La bonne","og_url":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/","og_site_name":"Sant\u00e9Onaturel","article_publisher":"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/","article_author":"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/about\/","article_published_time":"2017-07-19T09:13:33+00:00","article_modified_time":"2020-11-23T13:57:10+00:00","og_image":[{"width":1438,"height":1920,"url":"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2017\/04\/rocks-1524171_1920.jpg","type":"image\/jpeg"}],"author":"Marjorie DECLOQUEMENT","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marjorie DECLOQUEMENT","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/","url":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/","name":"\u00c9quilibre acido-basique mais de quoi s'agit-il ? - Sant\u00e9Onaturel","isPartOf":{"@id":"https:\/\/naturopathe35.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#primaryimage"},"image":{"@id":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#primaryimage"},"thumbnailUrl":"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2017\/04\/rocks-1524171_1920.jpg","datePublished":"2017-07-19T09:13:33+00:00","dateModified":"2020-11-23T13:57:10+00:00","author":{"@id":"https:\/\/naturopathe35.fr\/#\/schema\/person\/4466d62599687978be8f5a0f1df3f7ca"},"breadcrumb":{"@id":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#primaryimage","url":"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2017\/04\/rocks-1524171_1920.jpg","contentUrl":"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2017\/04\/rocks-1524171_1920.jpg","width":1438,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/naturopathe35.fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9quilibre acido-basique mais de quoi s&rsquo;agit-il ?"}]},{"@type":"WebSite","@id":"https:\/\/naturopathe35.fr\/#website","url":"https:\/\/naturopathe35.fr\/","name":"Sant\u00e9Onaturel","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturopathe35.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/naturopathe35.fr\/#\/schema\/person\/4466d62599687978be8f5a0f1df3f7ca","name":"Marjorie DECLOQUEMENT","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/naturopathe35.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/da8b5dfb971dc234578fd220ae090cd190a7c2abd7954496397a2b38e10aac2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/da8b5dfb971dc234578fd220ae090cd190a7c2abd7954496397a2b38e10aac2f?s=96&d=mm&r=g","caption":"Marjorie DECLOQUEMENT"},"sameAs":["https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/about\/","https:\/\/www.instagram.com\/santeonaturel_rennes\/","https:\/\/www.linkedin.com\/in\/marjorie-decloquement-b6482484\/"],"url":"https:\/\/naturopathe35.fr\/index.php\/author\/marjorie\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/posts\/1454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1454"}],"version-history":[{"count":23,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/posts\/1454\/revisions"}],"predecessor-version":[{"id":3352,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/posts\/1454\/revisions\/3352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/media\/1455"}],"wp:attachment":[{"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}