{"id":2464,"date":"2019-02-26T10:55:21","date_gmt":"2019-02-26T09:55:21","guid":{"rendered":"https:\/\/naturopathe35.fr\/?p=2464"},"modified":"2021-09-28T21:17:03","modified_gmt":"2021-09-28T20:17:03","slug":"manges-tes-legumes-oui-mais-pourquoi","status":"publish","type":"post","link":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/","title":{"rendered":"<H2>Manges tes l\u00e9gumes ! Oui mais pourquoi?<\/H2>"},"content":{"rendered":"<p>Quelque soit le mod\u00e8le alimentaire que l&rsquo;on suit (v\u00e9g\u00e9tarien, hypotoxique, vegan, pal\u00e9o &#8230;), tous les experts sant\u00e9 semblent d&rsquo;accord:\u00a0 <strong>les l\u00e9gumes sont indispensables a une sant\u00e9 optimale.<\/strong><\/p>\n<h3>Quels sont les atout des fruits et des l\u00e9gumes ?<\/h3>\n<ul>\n<li>Ils permettent de maintenir notre \u00e9quilibre acido-basique en apportant des min\u00e9raux et en limitant l&rsquo;<a href=\"https:\/\/naturopathe35.fr\/index.php\/2017\/07\/19\/equilibre-acido-basique-mais-de-quoi-sagit-il\/\">acidose m\u00e9tabolique latente nutritionnel<\/a> \/ Exception pour les tomates cuites et hors saison, les \u00e9pinards cuits, la rhubarbe, l&rsquo;oseille, la choucroute (mais elle apporte de bonnes bact\u00e9ries) &#8230; <strong>en mati\u00e8re d&rsquo;alimentation tout est question d&rsquo;\u00e9quilibre<\/strong> !<\/li>\n<li>Ils sont riches en vitamines, min\u00e9raux, oligo-\u00e9l\u00e9ments &#8230; <strong>Les micronutriments nous sont indispensables<\/strong>. Sans eux, la majorit\u00e9 des r\u00e9actions chimiques vitales n\u2019auraient pas lieu ou mettraient plusieurs si\u00e8cles pour se r\u00e9aliser ! Aucun min\u00e9ral et aucun oligo\u00e9l\u00e9ment n&rsquo;est \u00e9labor\u00e9 par l&rsquo;organisme et pourtant nos cellules ne peuvent pas s&rsquo;en passer. L&rsquo;alimentation, sous r\u00e9serve d&rsquo;une bonne cuisson, de bons produits locaux frais et biologiques, d&rsquo;une muqueuse intestinale saine &#8230; nous apportent <strong>ces nutriments essentiels \u00e0 une bonne sant\u00e9<\/strong>.<\/li>\n<li>R\u00e9gulation du transit par leur apport en fibres<\/li>\n<li>Les l\u00e9gumes et les fruits limitent l&rsquo;oxydation et le vieillissement de l&rsquo;organisme gr\u00e2ce \u00e0 leurs <strong>antioxydants, <\/strong>ils favorisent \u00e9galement le bon fonctionnement du syst\u00e8me immunitaire.<\/li>\n<li>Ils hydratent l&rsquo;organisme de part leur <strong>richesse en eau<\/strong><\/li>\n<li>Les l\u00e9gumes ont une densit\u00e9 nutritionnelle \u00e9lev\u00e9 car riches en nutriments et pauvres en calorie<\/li>\n<li>Ils favorisent la sati\u00e9t\u00e9 et aident \u00e0 r\u00e9guler le poids<\/li>\n<\/ul>\n<h3><strong>Des l\u00e9gumes verts dans votre assiette !<\/strong><\/h3>\n<p><img decoding=\"async\" class=\"lazyload aligncenter wp-image-2469 size-medium\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27144%27%20viewBox%3D%270%200%20300%20144%27%3E%3Crect%20width%3D%27300%27%20height%3D%27144%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/leg-vert-300x144.jpg\" alt=\"\" width=\"300\" height=\"144\" \/><\/p>\n<p>Les l\u00e9gumes verts (salade verte, haricot vert, asperge&#8230;)\u00a0 sont riches en <strong>chlorophylle<\/strong> ; on peut faire un parall\u00e8le avec l&rsquo;h\u00e9moglobine qui est toujours rattach\u00e9e \u00e0 une mol\u00e9cule de fer, la chlorophylle chez les v\u00e9g\u00e9taux est elle rattach\u00e9e \u00e0 une mol\u00e9cule de magn\u00e9sium. Ainsi, la chlorophylle, appel\u00e9e \u00e9galement le sang vert, <strong>apporte de l&rsquo;oxyg\u00e8ne au sang<\/strong> en stimulant la production d&rsquo;h\u00e9moglobine et de globules rouges chez les personnes an\u00e9mi\u00e9es.<\/p>\n<p>Par le biais de la chlorophylle, les l\u00e9gumes verts vont apporter du magn\u00e9sium. <strong>C&rsquo;est le quatri\u00e8me min\u00e9ral le plus r\u00e9pandu dans notre organisme<\/strong>; il se trouve essentiellement au niveau des os, dents mais aussi dans les muscles. Le corps ne produit pas de magn\u00e9sium mais il en perd \u00e9norm\u00e9ment par l&rsquo; \u00e9limination r\u00e9nale et en cas de stress, efforts sportifs intenses, diarrh\u00e9e &#8230; Ce min\u00e9ral intervient dans plus de <strong>300 r\u00e9actions biochimiques cellulaires;<\/strong> il intervient entre autres dans le bon fonctionnement des syst\u00e8mes musculaires et nerveux, la production d\u2019\u00e9nergie, la sant\u00e9 osseuse, la synth\u00e8se des prot\u00e9ines et de l\u2019ADN. Une carence induit g\u00e9n\u00e9ralement une grande fatigue avec\u00a0 une grande sensibilit\u00e9 nerveuse, de l&rsquo;irritabilit\u00e9, une baisse de moral, des troubles de l\u2019humeur,une sensibilit\u00e9 au stress, des crampes,un sommeil perturb\u00e9 &#8230;<\/p>\n<p>Les l\u00e9gumes riches en chlorophylle vont \u00e9galement <strong>drainer et nettoyer en douceur les intestins<\/strong>. La chlorophylle a une action <strong>antibact\u00e9rienne<\/strong> et favorise la cicatrisation des muqueuses.<\/p>\n<p>Les l\u00e9gumes verts fonc\u00e9s sont particuli\u00e8rement riches en vitamines du groupe B qui aident \u00e0 la production de s\u00e9rotonine et am\u00e9liorent l\u2019humeur.<\/p>\n<h3><strong>Un arc-en-ciel de couleurs!<\/strong><\/h3>\n<p><img decoding=\"async\" class=\"lazyload aligncenter wp-image-2471 size-medium\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27169%27%20viewBox%3D%270%200%20300%20169%27%3E%3Crect%20width%3D%27300%27%20height%3D%27169%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/farmers-market-1329008_1280-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" \/><\/p>\n<p>Les l\u00e9gumes color\u00e9s sont riches en antioxydants et permettent de <strong>r\u00e9duire le stress oxydatif<\/strong> induit par les radicaux libre. Ces derniers sont des mol\u00e9cules instables qui sont produits naturellement en plus ou moins grande quantit\u00e9 par notre organisme. Cette instabilit\u00e9 est \u00e0 l\u2019origine du stress oxydatif. Cette oxydation est \u00e0 l&rsquo;origine du vieillissement naturel mais peut \u00e9galement favoriser certaines maladies: cancer du aux attaques de l&rsquo;ADN par les radicaux libres, maladies d\u00e9g\u00e9n\u00e9ratives li\u00e9es \u00e0 l\u2019\u00e2ge (Alzheimer, d\u00e9mence, ath\u00e9roscl\u00e9rose&#8230;), maladies cardio-vasculaire &#8230; Notre mode de vie \u00ab\u00a0moderne\u00a0\u00bb et les conditions environnementales peuvent favoriser la prolif\u00e9ration de ces radicaux libres: le tabac, l&rsquo;exposition prolong\u00e9e au soleil, la pollution, le stress&#8230;. Chaque inspiration d&rsquo;air pollu\u00e9 ou de fum\u00e9e de cigarette laisse entrer 10 puissance 15 radicaux libres dans les poumons.<\/p>\n<p>=&gt; Autant de raisons de consommer des l\u00e9gumes color\u00e9s et riches en antioxydants. Pensez en particulier au persil, poivron, baies rouges, artichaut, poireaux, brocoli, l\u00e9gumes verts et\u00a0 herbes aromatiques &#8230;<\/p>\n<p>Les l\u00e9gumes sont un r\u00e9el atout sant\u00e9 et quel plaisir\u00a0 de fl\u00e2ner sur les march\u00e9s ou d&rsquo;aller chez son mara\u00eecher !!! AMAP et r\u00e9seaux locaux fleurissent un peu partout en France, ils permettent d&rsquo;avoir des produits frais, de saison et de qualit\u00e9 alors <strong>plus d&rsquo;excuses<\/strong> pour ne pas les mettre \u00e0 votre menu. En se cuisinant de milles et une fa\u00e7on, ils \u00e9gayent nos assiettes et notre sant\u00e9 alors ne nous en privons pas, <strong>\u00e0 consommer sans mod\u00e9ration !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelque soit le mod\u00e8le alimentaire que l&rsquo;on suit (v\u00e9g\u00e9tarien, hypotoxique, vegan, pal\u00e9o &#8230;), tous les experts sant\u00e9 semblent d&rsquo;accord:\u00a0 les l\u00e9gumes sont indispensables a une<\/p>\n","protected":false},"author":2,"featured_media":3640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[72],"tags":[105,106,104,38,62],"class_list":["post-2464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-naturopathie","tag-alcalinisant","tag-fruits","tag-legumes","tag-nutrition","tag-sante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manges tes l\u00e9gumes ! Oui mais pourquoi? - Sant\u00e9Onaturel<\/title>\n<meta name=\"description\" content=\"Quelque soit le mod\u00e8le alimentaire que l&#039;on suit, tous les experts sant\u00e9 semblent d&#039;accord:\u00a0 les l\u00e9gumes sont indispensables a une sant\u00e9 optimale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manges tes l\u00e9gumes ! Oui mais pourquoi? - Sant\u00e9Onaturel\" \/>\n<meta property=\"og:description\" content=\"Quelque soit le mod\u00e8le alimentaire que l&#039;on suit, tous les experts sant\u00e9 semblent d&#039;accord:\u00a0 les l\u00e9gumes sont indispensables a une sant\u00e9 optimale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/\" \/>\n<meta property=\"og:site_name\" content=\"Sant\u00e9Onaturel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/about\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-26T09:55:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-28T20:17:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/Sans-titre57.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marjorie DECLOQUEMENT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marjorie DECLOQUEMENT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/\",\"url\":\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/\",\"name\":\"Manges tes l\u00e9gumes ! Oui mais pourquoi? - Sant\u00e9Onaturel\",\"isPartOf\":{\"@id\":\"https:\/\/naturopathe35.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/Sans-titre57.png\",\"datePublished\":\"2019-02-26T09:55:21+00:00\",\"dateModified\":\"2021-09-28T20:17:03+00:00\",\"author\":{\"@id\":\"https:\/\/naturopathe35.fr\/#\/schema\/person\/4466d62599687978be8f5a0f1df3f7ca\"},\"description\":\"Quelque soit le mod\u00e8le alimentaire que l'on suit, tous les experts sant\u00e9 semblent d'accord:\u00a0 les l\u00e9gumes sont indispensables a une sant\u00e9 optimale.\",\"breadcrumb\":{\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#primaryimage\",\"url\":\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/Sans-titre57.png\",\"contentUrl\":\"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/Sans-titre57.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/naturopathe35.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manges tes l\u00e9gumes ! Oui mais pourquoi?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/naturopathe35.fr\/#website\",\"url\":\"https:\/\/naturopathe35.fr\/\",\"name\":\"Sant\u00e9Onaturel\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/naturopathe35.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/naturopathe35.fr\/#\/schema\/person\/4466d62599687978be8f5a0f1df3f7ca\",\"name\":\"Marjorie DECLOQUEMENT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/naturopathe35.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/da8b5dfb971dc234578fd220ae090cd190a7c2abd7954496397a2b38e10aac2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/da8b5dfb971dc234578fd220ae090cd190a7c2abd7954496397a2b38e10aac2f?s=96&d=mm&r=g\",\"caption\":\"Marjorie DECLOQUEMENT\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/about\/\",\"https:\/\/www.instagram.com\/santeonaturel_rennes\/\",\"https:\/\/www.linkedin.com\/in\/marjorie-decloquement-b6482484\/\"],\"url\":\"https:\/\/naturopathe35.fr\/index.php\/author\/marjorie\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manges tes l\u00e9gumes ! Oui mais pourquoi? - Sant\u00e9Onaturel","description":"Quelque soit le mod\u00e8le alimentaire que l'on suit, tous les experts sant\u00e9 semblent d'accord:\u00a0 les l\u00e9gumes sont indispensables a une sant\u00e9 optimale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/","og_locale":"fr_FR","og_type":"article","og_title":"Manges tes l\u00e9gumes ! Oui mais pourquoi? - Sant\u00e9Onaturel","og_description":"Quelque soit le mod\u00e8le alimentaire que l'on suit, tous les experts sant\u00e9 semblent d'accord:\u00a0 les l\u00e9gumes sont indispensables a une sant\u00e9 optimale.","og_url":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/","og_site_name":"Sant\u00e9Onaturel","article_publisher":"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/","article_author":"https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/about\/","article_published_time":"2019-02-26T09:55:21+00:00","article_modified_time":"2021-09-28T20:17:03+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/Sans-titre57.png","type":"image\/png"}],"author":"Marjorie DECLOQUEMENT","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marjorie DECLOQUEMENT","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/","url":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/","name":"Manges tes l\u00e9gumes ! Oui mais pourquoi? - Sant\u00e9Onaturel","isPartOf":{"@id":"https:\/\/naturopathe35.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#primaryimage"},"image":{"@id":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#primaryimage"},"thumbnailUrl":"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/Sans-titre57.png","datePublished":"2019-02-26T09:55:21+00:00","dateModified":"2021-09-28T20:17:03+00:00","author":{"@id":"https:\/\/naturopathe35.fr\/#\/schema\/person\/4466d62599687978be8f5a0f1df3f7ca"},"description":"Quelque soit le mod\u00e8le alimentaire que l'on suit, tous les experts sant\u00e9 semblent d'accord:\u00a0 les l\u00e9gumes sont indispensables a une sant\u00e9 optimale.","breadcrumb":{"@id":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#primaryimage","url":"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/Sans-titre57.png","contentUrl":"https:\/\/naturopathe35.fr\/wp-content\/uploads\/2019\/02\/Sans-titre57.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/naturopathe35.fr\/index.php\/2019\/02\/26\/manges-tes-legumes-oui-mais-pourquoi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/naturopathe35.fr\/"},{"@type":"ListItem","position":2,"name":"Manges tes l\u00e9gumes ! Oui mais pourquoi?"}]},{"@type":"WebSite","@id":"https:\/\/naturopathe35.fr\/#website","url":"https:\/\/naturopathe35.fr\/","name":"Sant\u00e9Onaturel","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturopathe35.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/naturopathe35.fr\/#\/schema\/person\/4466d62599687978be8f5a0f1df3f7ca","name":"Marjorie DECLOQUEMENT","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/naturopathe35.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/da8b5dfb971dc234578fd220ae090cd190a7c2abd7954496397a2b38e10aac2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/da8b5dfb971dc234578fd220ae090cd190a7c2abd7954496397a2b38e10aac2f?s=96&d=mm&r=g","caption":"Marjorie DECLOQUEMENT"},"sameAs":["https:\/\/www.facebook.com\/pg\/marjoriedecloquement\/about\/","https:\/\/www.instagram.com\/santeonaturel_rennes\/","https:\/\/www.linkedin.com\/in\/marjorie-decloquement-b6482484\/"],"url":"https:\/\/naturopathe35.fr\/index.php\/author\/marjorie\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/posts\/2464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2464"}],"version-history":[{"count":17,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/posts\/2464\/revisions"}],"predecessor-version":[{"id":3125,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/posts\/2464\/revisions\/3125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/media\/3640"}],"wp:attachment":[{"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naturopathe35.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}